{"id":145,"date":"2024-04-30T15:56:50","date_gmt":"2024-04-30T13:56:50","guid":{"rendered":"http:\/\/localhost:8888\/wordpress-3\/?page_id=145"},"modified":"2024-08-20T17:53:46","modified_gmt":"2024-08-20T15:53:46","slug":"nos-services","status":"publish","type":"page","link":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/","title":{"rendered":"Nos Services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"145\" class=\"elementor elementor-145\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15527d1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"15527d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:471,&quot;url&quot;:&quot;https:\\\/\\\/www.isirconseils.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/woman-climber-success-silhouette-in-mountains-oce-2023-11-27-04-49-52-utc.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7351bf e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b7351bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19401d4 elementor-widget elementor-widget-heading\" data-id=\"19401d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ISIR Conseils propose une gamme compl\u00e8te de services pour vous aider \u00e0 r\u00e9ussir en affaires <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a50612c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a50612c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b75569e elementor-widget elementor-widget-text-editor\" data-id=\"b75569e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Chez ISIR Conseils, nous proposons une gamme compl\u00e8te de services de coaching, de formations et des ateliers, sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins des Dirigeants, Entrepreneurs, Managers et des organisations.<\/span><\/p><p><span style=\"font-weight: 400;\">Que vous souhaitiez lancer votre activit\u00e9, optimiser vos performances ou transformer votre \u00e9quipe, nous avons une solution adapt\u00e9e \u00e0 vos ambitions.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5e6cb9 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a5e6cb9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a2398e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"9a2398e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a64f596 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"a64f596\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fabb029 elementor-widget elementor-widget-heading\" data-id=\"fabb029\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Le coaching individuel<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359bc16 elementor-widget elementor-widget-text-editor\" data-id=\"359bc16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nos services de coaching individuel sont orient\u00e9s vers des r\u00e9sultats concrets et personnalis\u00e9s, avec des th\u00e8mes cl\u00e9s tels que :<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4bab5e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c4bab5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Accompagnement au changement :<\/b> Facilitez vos transitions professionnelles et personnelles.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Renforcement de la confiance en soi : <\/b>Lib\u00e9rez votre potentiel et d\u00e9passez vos limites.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Gestion du stress : <\/b>Trouvez l'\u00e9quilibre entre performance et bien-\u00eatre.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>D\u00e9veloppement des comp\u00e9tences en leadership :<\/b> Devenez un leader inspirant et efficace.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ae67bfc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ae67bfc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcdc094 elementor-widget elementor-widget-image\" data-id=\"fcdc094\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-scaled.jpg\" class=\"attachment-full size-full wp-image-878\" alt=\"\" srcset=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-scaled.jpg 2560w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-300x200.jpg 300w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-1024x683.jpg 1024w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-768x512.jpg 768w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-1536x1024.jpg 1536w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8225c1c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"8225c1c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4787010 elementor-widget elementor-widget-text-editor\" data-id=\"4787010\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Quel que soit votre r\u00f4le \u2013 dirigeant, entrepreneur, manager d\u00e9butant ou cadre exp\u00e9riment\u00e9 \u2013 nous vous accompagnons avec des solutions sur mesure, adapt\u00e9es \u00e0 vos d\u00e9fis sp\u00e9cifiques.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2620c71 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2620c71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5e25f8 elementor-widget elementor-widget-button\" data-id=\"c5e25f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.isirconseils.com\/index.php\/coaching-individuel\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En Savoir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98f68a0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"98f68a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-752a219 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"752a219\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-32f4973 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"32f4973\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c66859b elementor-widget elementor-widget-image\" data-id=\"c66859b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"340\" src=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/ISIR-objectif-construire-sa-route-generer-du-chiffre-min.jpg\" class=\"attachment-full size-full wp-image-775\" alt=\"\" srcset=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/ISIR-objectif-construire-sa-route-generer-du-chiffre-min.jpg 500w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/ISIR-objectif-construire-sa-route-generer-du-chiffre-min-300x204.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ae7991 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6ae7991\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f8e659 elementor-widget elementor-widget-heading\" data-id=\"4f8e659\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Le coaching Business<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-268a992 elementor-widget elementor-widget-text-editor\" data-id=\"268a992\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Notre coaching business est con\u00e7u pour les entrepreneurs et dirigeants d\u00e9sireux de transformer les incertitudes en opportunit\u00e9s de croissance.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b724f9e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b724f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Clarifier votre vision et vos objectifs :<\/b> Donnez une direction claire \u00e0 votre entreprise.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Affinez votre direction et votre orientation :<\/b> Prenez des d\u00e9cisions \u00e9clair\u00e9es et align\u00e9es sur vos ambitions.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Inspirez la cr\u00e9ativit\u00e9 et l'innovation dans vos processus internes : <\/b>Stimulez l'innovation au c\u0153ur de vos processus.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>D\u00e9veloppez des strat\u00e9gies de croissance puissantes : <\/b>Concevez des plans robustes pour une croissance durable.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Optimisez vos ressources et maximisez votre rentabilit\u00e9 :<\/b> Utilisez vos ressources de mani\u00e8re efficiente pour des r\u00e9sultats tangibles.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Planifiez et organisez pour le succ\u00e8s :<\/b> Structurez vos actions pour garantir un avenir prosp\u00e8re.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2a948e e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"f2a948e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c8dc6b8 elementor-widget elementor-widget-text-editor\" data-id=\"c8dc6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Transformez vos doutes en une force motrice pour une prise de d\u00e9cision strat\u00e9gique et maintenez une motivation \u00e9lev\u00e9e, m\u00eame face aux d\u00e9fis.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-afbea24 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"afbea24\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d68b98 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7d68b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.isirconseils.com\/index.php\/coaching-business\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En Savoir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef34ff4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef34ff4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0fccf66 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"0fccf66\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b672037 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"b672037\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f8194f0 elementor-widget elementor-widget-image\" data-id=\"f8194f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/corporate-business-people-min-1024x576.jpg\" class=\"attachment-large size-large wp-image-1188\" alt=\"\" srcset=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/corporate-business-people-min-1024x576.jpg 1024w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/corporate-business-people-min-300x169.jpg 300w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/corporate-business-people-min-768x432.jpg 768w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/corporate-business-people-min-1536x865.jpg 1536w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/corporate-business-people-min-2048x1153.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed17666 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ed17666\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78a5d2d elementor-widget elementor-widget-heading\" data-id=\"78a5d2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Coaching En Entreprise<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2e1d2f elementor-widget elementor-widget-text-editor\" data-id=\"e2e1d2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Envie de transformer votre \u00e9quipe en une force coh\u00e9sive et performante, align\u00e9e sur les objectifs de votre entreprise ?<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583450c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"583450c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Am\u00e9lioration de la communication : <\/b> Facilitez les \u00e9changes et renforcez la collaboration.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Encouragement de la collaboration : <\/b>Cr\u00e9ez une dynamique d'\u00e9quipe positive et productive.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>D\u00e9veloppement des comp\u00e9tences en leadership : <\/b> Formez des leaders capables de guider avec succ\u00e8s.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Gestion du changement :<\/b> Accompagnez vos \u00e9quipes dans les transitions organisationnelles.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Motivation des \u00e9quipes :<\/b> Augmentez l\u2019engagement et la satisfaction au travail.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a96ad29 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a96ad29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a6c3d4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5a6c3d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.isirconseils.com\/index.php\/coachingen-entreprise\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En Savoir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d18f621 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d18f621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-666c98b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"666c98b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca0eb5a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"ca0eb5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a20486c elementor-widget elementor-widget-heading\" data-id=\"a20486c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Atelier et Formation<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0e28e4 elementor-widget elementor-widget-text-editor\" data-id=\"e0e28e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Des formations sur mesure et des ateliers dynamiques pour transformer votre entreprise :<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e10a7bc elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e10a7bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b> Ma\u00eetrise du temps et efficacit\u00e9 : <\/b> Dominez votre agenda pour une productivit\u00e9 maximale.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Leadership et communication :<\/b> Devenez un leader inspirant et un communicateur d'exception.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Gestion du stress : <\/b> Restez ma\u00eetre de vos \u00e9motions, m\u00eame sous pression.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Optimisation fiscale : <\/b> Maximisez vos avantages fiscaux.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Plan d'affaires solide :<\/b> Posez des fondations in\u00e9branlables pour votre succ\u00e8s.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Vision strat\u00e9gique :<\/b> Naviguez avec confiance vers l'avenir.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40e1847 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"40e1847\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4f8cff6 elementor-widget elementor-widget-image\" data-id=\"4f8cff6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"202\" src=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/Photo-atelier-et-formation-min-300x202.jpg\" class=\"attachment-medium size-medium wp-image-1213\" alt=\"\" srcset=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/Photo-atelier-et-formation-min-300x202.jpg 300w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/Photo-atelier-et-formation-min-1024x690.jpg 1024w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/Photo-atelier-et-formation-min-768x517.jpg 768w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/Photo-atelier-et-formation-min-1536x1035.jpg 1536w, https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/08\/Photo-atelier-et-formation-min-2048x1379.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b96f99b e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b96f99b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75bc7d5 elementor-widget elementor-widget-button\" data-id=\"75bc7d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.isirconseils.com\/index.php\/atelieret-formation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En Savoir Plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5259d16 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5259d16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3bc5bb3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3bc5bb3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f0d0c7 elementor-widget elementor-widget-heading\" data-id=\"3f0d0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La m\u00e9thode ISIR : Quatre \u00c9tapes pour R\u00e9ussir le Passage \u00e0 l\u2019Action<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66536b71 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"66536b71\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6c93076a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6c93076a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a11ca7 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7a11ca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-search\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M505 442.7L405.3 343c-4.5-4.5-10.6-7-17-7H372c27.6-35.3 44-79.7 44-128C416 93.1 322.9 0 208 0S0 93.1 0 208s93.1 208 208 208c48.3 0 92.7-16.4 128-44v16.3c0 6.4 2.5 12.5 7 17l99.7 99.7c9.4 9.4 24.6 9.4 33.9 0l28.3-28.3c9.4-9.4 9.4-24.6.1-34zM208 336c-70.7 0-128-57.2-128-128 0-70.7 57.2-128 128-128 70.7 0 128 57.2 128 128 0 70.7-57.2 128-128 128z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tIdentifier\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4db06de1 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4db06de1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8024911 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8024911\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-list-ul\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M48 48a48 48 0 1 0 48 48 48 48 0 0 0-48-48zm0 160a48 48 0 1 0 48 48 48 48 0 0 0-48-48zm0 160a48 48 0 1 0 48 48 48 48 0 0 0-48-48zm448 16H176a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h320a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16zm0-320H176a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h320a16 16 0 0 0 16-16V80a16 16 0 0 0-16-16zm0 160H176a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h320a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSimplifier\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13ce6c36 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"13ce6c36\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7652f6b elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7652f6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-route\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 320h-96c-17.6 0-32-14.4-32-32s14.4-32 32-32h96s96-107 96-160-43-96-96-96-96 43-96 96c0 25.5 22.2 63.4 45.3 96H320c-52.9 0-96 43.1-96 96s43.1 96 96 96h96c17.6 0 32 14.4 32 32s-14.4 32-32 32H185.5c-16 24.8-33.8 47.7-47.3 64H416c52.9 0 96-43.1 96-96s-43.1-96-96-96zm0-256c17.7 0 32 14.3 32 32s-14.3 32-32 32-32-14.3-32-32 14.3-32 32-32zM96 256c-53 0-96 43-96 96s96 160 96 160 96-107 96-160-43-96-96-96zm0 128c-17.7 0-32-14.3-32-32s14.3-32 32-32 32 14.3 32 32-14.3 32-32 32z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tImpulser\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-254e6365 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"254e6365\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-685c42ab elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"685c42ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-sun\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 160c-52.9 0-96 43.1-96 96s43.1 96 96 96 96-43.1 96-96-43.1-96-96-96zm246.4 80.5l-94.7-47.3 33.5-100.4c4.5-13.6-8.4-26.5-21.9-21.9l-100.4 33.5-47.4-94.8c-6.4-12.8-24.6-12.8-31 0l-47.3 94.7L92.7 70.8c-13.6-4.5-26.5 8.4-21.9 21.9l33.5 100.4-94.7 47.4c-12.8 6.4-12.8 24.6 0 31l94.7 47.3-33.5 100.5c-4.5 13.6 8.4 26.5 21.9 21.9l100.4-33.5 47.3 94.7c6.4 12.8 24.6 12.8 31 0l47.3-94.7 100.4 33.5c13.6 4.5 26.5-8.4 21.9-21.9l-33.5-100.4 94.7-47.3c13-6.5 13-24.7.2-31.1zm-155.9 106c-49.9 49.9-131.1 49.9-181 0-49.9-49.9-49.9-131.1 0-181 49.9-49.9 131.1-49.9 181 0 49.9 49.9 49.9 131.1 0 181z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRayonner\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2cd9010 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2cd9010\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c0fca3d elementor-widget elementor-widget-text-editor\" data-id=\"c0fca3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ol><li><b>Identifier :<\/b><b>\u00a0<\/b><span style=\"font-weight: 400;\">Nous r\u00e9v\u00e9lons vos forces et d\u00e9tectons les opportunit\u00e9s pour b\u00e2tir une base solide.<\/span><\/li><li><b> Simplifier : <\/b><span style=\"font-size: 16px;\">Nous \u00e9purons vos processus et relations pour vous concentrer sur l&rsquo;essentiel.<\/span><\/li><li><b> Impulser : \u00a0<span style=\"font-weight: 400;\">Nous transformons les id\u00e9es en actions concr\u00e8tes pour acc\u00e9l\u00e9rer votre progression.<\/span><\/b><\/li><li><b>Rayonner: <\/b><span style=\"font-weight: 400;\">Nous vous accompagnons pour que votre succ\u00e8s soit reconnu et durable.<\/span><\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7177e3 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"e7177e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ISIR Conseils propose une gamme compl\u00e8te de services pour vous aider \u00e0 r\u00e9ussir en affaires Chez ISIR Conseils, nous proposons une gamme compl\u00e8te de services de coaching, de formations et des ateliers, sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins des Dirigeants, Entrepreneurs, Managers et des organisations. Que vous souhaitiez lancer votre activit\u00e9, optimiser vos performances ou transformer votre \u00e9quipe, nous avons une solution adapt\u00e9e \u00e0 vos ambitions. Le coaching individuel Nos services de coaching individuel sont orient\u00e9s vers des r\u00e9sultats concrets et personnalis\u00e9s, avec des th\u00e8mes cl\u00e9s tels que : Accompagnement au changement : Facilitez vos transitions professionnelles et personnelles. Renforcement de la confiance en soi : Lib\u00e9rez votre potentiel et d\u00e9passez vos limites. Gestion du stress : Trouvez l&rsquo;\u00e9quilibre entre performance et bien-\u00eatre. D\u00e9veloppement des comp\u00e9tences en leadership : Devenez un leader inspirant et efficace. Quel que soit votre r\u00f4le \u2013 dirigeant, entrepreneur, manager d\u00e9butant ou cadre exp\u00e9riment\u00e9 \u2013 nous vous accompagnons avec des solutions sur mesure, adapt\u00e9es \u00e0 vos d\u00e9fis sp\u00e9cifiques. En Savoir Plus Le coaching Business Notre coaching business est con\u00e7u pour les entrepreneurs et dirigeants d\u00e9sireux de transformer les incertitudes en opportunit\u00e9s de croissance. Clarifier votre vision et vos objectifs : Donnez une direction claire \u00e0 votre entreprise. Affinez votre direction et votre orientation : Prenez des d\u00e9cisions \u00e9clair\u00e9es et align\u00e9es sur vos ambitions. Inspirez la cr\u00e9ativit\u00e9 et l&rsquo;innovation dans vos processus internes : Stimulez l&rsquo;innovation au c\u0153ur de vos processus. D\u00e9veloppez des strat\u00e9gies de croissance puissantes : Concevez des plans robustes pour une croissance durable. Optimisez vos ressources et maximisez votre rentabilit\u00e9 : Utilisez vos ressources de mani\u00e8re efficiente pour des r\u00e9sultats tangibles. Planifiez et organisez pour le succ\u00e8s : Structurez vos actions pour garantir un avenir prosp\u00e8re. Transformez vos doutes en une force motrice pour une prise de d\u00e9cision strat\u00e9gique et maintenez une motivation \u00e9lev\u00e9e, m\u00eame face aux d\u00e9fis. En Savoir Plus Coaching En Entreprise Envie de transformer votre \u00e9quipe en une force coh\u00e9sive et performante, align\u00e9e sur les objectifs de votre entreprise ? Am\u00e9lioration de la communication : Facilitez les \u00e9changes et renforcez la collaboration. Encouragement de la collaboration : Cr\u00e9ez une dynamique d&rsquo;\u00e9quipe positive et productive. D\u00e9veloppement des comp\u00e9tences en leadership : Formez des leaders capables de guider avec succ\u00e8s. Gestion du changement : Accompagnez vos \u00e9quipes dans les transitions organisationnelles. Motivation des \u00e9quipes : Augmentez l\u2019engagement et la satisfaction au travail. En Savoir Plus Atelier et Formation Des formations sur mesure et des ateliers dynamiques pour transformer votre entreprise : Ma\u00eetrise du temps et efficacit\u00e9 : Dominez votre agenda pour une productivit\u00e9 maximale. Leadership et communication : Devenez un leader inspirant et un communicateur d&rsquo;exception. Gestion du stress : Restez ma\u00eetre de vos \u00e9motions, m\u00eame sous pression. Optimisation fiscale : Maximisez vos avantages fiscaux. Plan d&rsquo;affaires solide : Posez des fondations in\u00e9branlables pour votre succ\u00e8s. Vision strat\u00e9gique : Naviguez avec confiance vers l&rsquo;avenir. En Savoir Plus La m\u00e9thode ISIR : Quatre \u00c9tapes pour R\u00e9ussir le Passage \u00e0 l\u2019Action Identifier Simplifier Impulser Rayonner Identifier :\u00a0Nous r\u00e9v\u00e9lons vos forces et d\u00e9tectons les opportunit\u00e9s pour b\u00e2tir une base solide. Simplifier : Nous \u00e9purons vos processus et relations pour vous concentrer sur l&rsquo;essentiel. Impulser : \u00a0Nous transformons les id\u00e9es en actions concr\u00e8tes pour acc\u00e9l\u00e9rer votre progression. Rayonner: Nous vous accompagnons pour que votre succ\u00e8s soit reconnu et durable.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-145","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos Services - ISIR Conseils<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.isirconseils.com\/index.php\/nos-services\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos Services - ISIR Conseils\" \/>\n<meta property=\"og:description\" content=\"ISIR Conseils propose une gamme compl\u00e8te de services pour vous aider \u00e0 r\u00e9ussir en affaires Chez ISIR Conseils, nous proposons une gamme compl\u00e8te de services de coaching, de formations et des ateliers, sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins des Dirigeants, Entrepreneurs, Managers et des organisations. Que vous souhaitiez lancer votre activit\u00e9, optimiser vos performances ou transformer votre \u00e9quipe, nous avons une solution adapt\u00e9e \u00e0 vos ambitions. Le coaching individuel Nos services de coaching individuel sont orient\u00e9s vers des r\u00e9sultats concrets et personnalis\u00e9s, avec des th\u00e8mes cl\u00e9s tels que : Accompagnement au changement : Facilitez vos transitions professionnelles et personnelles. Renforcement de la confiance en soi : Lib\u00e9rez votre potentiel et d\u00e9passez vos limites. Gestion du stress : Trouvez l&rsquo;\u00e9quilibre entre performance et bien-\u00eatre. D\u00e9veloppement des comp\u00e9tences en leadership : Devenez un leader inspirant et efficace. Quel que soit votre r\u00f4le \u2013 dirigeant, entrepreneur, manager d\u00e9butant ou cadre exp\u00e9riment\u00e9 \u2013 nous vous accompagnons avec des solutions sur mesure, adapt\u00e9es \u00e0 vos d\u00e9fis sp\u00e9cifiques. En Savoir Plus Le coaching Business Notre coaching business est con\u00e7u pour les entrepreneurs et dirigeants d\u00e9sireux de transformer les incertitudes en opportunit\u00e9s de croissance. Clarifier votre vision et vos objectifs : Donnez une direction claire \u00e0 votre entreprise. Affinez votre direction et votre orientation : Prenez des d\u00e9cisions \u00e9clair\u00e9es et align\u00e9es sur vos ambitions. Inspirez la cr\u00e9ativit\u00e9 et l&rsquo;innovation dans vos processus internes : Stimulez l&rsquo;innovation au c\u0153ur de vos processus. D\u00e9veloppez des strat\u00e9gies de croissance puissantes : Concevez des plans robustes pour une croissance durable. Optimisez vos ressources et maximisez votre rentabilit\u00e9 : Utilisez vos ressources de mani\u00e8re efficiente pour des r\u00e9sultats tangibles. Planifiez et organisez pour le succ\u00e8s : Structurez vos actions pour garantir un avenir prosp\u00e8re. Transformez vos doutes en une force motrice pour une prise de d\u00e9cision strat\u00e9gique et maintenez une motivation \u00e9lev\u00e9e, m\u00eame face aux d\u00e9fis. En Savoir Plus Coaching En Entreprise Envie de transformer votre \u00e9quipe en une force coh\u00e9sive et performante, align\u00e9e sur les objectifs de votre entreprise ? Am\u00e9lioration de la communication : Facilitez les \u00e9changes et renforcez la collaboration. Encouragement de la collaboration : Cr\u00e9ez une dynamique d&rsquo;\u00e9quipe positive et productive. D\u00e9veloppement des comp\u00e9tences en leadership : Formez des leaders capables de guider avec succ\u00e8s. Gestion du changement : Accompagnez vos \u00e9quipes dans les transitions organisationnelles. Motivation des \u00e9quipes : Augmentez l\u2019engagement et la satisfaction au travail. En Savoir Plus Atelier et Formation Des formations sur mesure et des ateliers dynamiques pour transformer votre entreprise : Ma\u00eetrise du temps et efficacit\u00e9 : Dominez votre agenda pour une productivit\u00e9 maximale. Leadership et communication : Devenez un leader inspirant et un communicateur d&rsquo;exception. Gestion du stress : Restez ma\u00eetre de vos \u00e9motions, m\u00eame sous pression. Optimisation fiscale : Maximisez vos avantages fiscaux. Plan d&rsquo;affaires solide : Posez des fondations in\u00e9branlables pour votre succ\u00e8s. Vision strat\u00e9gique : Naviguez avec confiance vers l&rsquo;avenir. En Savoir Plus La m\u00e9thode ISIR : Quatre \u00c9tapes pour R\u00e9ussir le Passage \u00e0 l\u2019Action Identifier Simplifier Impulser Rayonner Identifier :\u00a0Nous r\u00e9v\u00e9lons vos forces et d\u00e9tectons les opportunit\u00e9s pour b\u00e2tir une base solide. Simplifier : Nous \u00e9purons vos processus et relations pour vous concentrer sur l&rsquo;essentiel. Impulser : \u00a0Nous transformons les id\u00e9es en actions concr\u00e8tes pour acc\u00e9l\u00e9rer votre progression. Rayonner: Nous vous accompagnons pour que votre succ\u00e8s soit reconnu et durable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.isirconseils.com\/index.php\/nos-services\/\" \/>\n<meta property=\"og:site_name\" content=\"ISIR Conseils\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-20T15:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/\",\"url\":\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/\",\"name\":\"Nos Services - ISIR Conseils\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.isirconseils.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/services-min-scaled.jpg\",\"datePublished\":\"2024-04-30T13:56:50+00:00\",\"dateModified\":\"2024-08-20T15:53:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.isirconseils.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/services-min-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.isirconseils.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/services-min-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/index.php\\\/nos-services\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.isirconseils.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/#website\",\"url\":\"https:\\\/\\\/www.isirconseils.com\\\/\",\"name\":\"ISIR Conseils\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.isirconseils.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/#organization\",\"name\":\"ISIR Conseils\",\"url\":\"https:\\\/\\\/www.isirconseils.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.isirconseils.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-ISIR-web-2.png\",\"contentUrl\":\"https:\\\/\\\/www.isirconseils.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-ISIR-web-2.png\",\"width\":202,\"height\":224,\"caption\":\"ISIR Conseils\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isirconseils.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos Services - ISIR Conseils","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos Services - ISIR Conseils","og_description":"ISIR Conseils propose une gamme compl\u00e8te de services pour vous aider \u00e0 r\u00e9ussir en affaires Chez ISIR Conseils, nous proposons une gamme compl\u00e8te de services de coaching, de formations et des ateliers, sp\u00e9cialement con\u00e7us pour r\u00e9pondre aux besoins des Dirigeants, Entrepreneurs, Managers et des organisations. Que vous souhaitiez lancer votre activit\u00e9, optimiser vos performances ou transformer votre \u00e9quipe, nous avons une solution adapt\u00e9e \u00e0 vos ambitions. Le coaching individuel Nos services de coaching individuel sont orient\u00e9s vers des r\u00e9sultats concrets et personnalis\u00e9s, avec des th\u00e8mes cl\u00e9s tels que : Accompagnement au changement : Facilitez vos transitions professionnelles et personnelles. Renforcement de la confiance en soi : Lib\u00e9rez votre potentiel et d\u00e9passez vos limites. Gestion du stress : Trouvez l&rsquo;\u00e9quilibre entre performance et bien-\u00eatre. D\u00e9veloppement des comp\u00e9tences en leadership : Devenez un leader inspirant et efficace. Quel que soit votre r\u00f4le \u2013 dirigeant, entrepreneur, manager d\u00e9butant ou cadre exp\u00e9riment\u00e9 \u2013 nous vous accompagnons avec des solutions sur mesure, adapt\u00e9es \u00e0 vos d\u00e9fis sp\u00e9cifiques. En Savoir Plus Le coaching Business Notre coaching business est con\u00e7u pour les entrepreneurs et dirigeants d\u00e9sireux de transformer les incertitudes en opportunit\u00e9s de croissance. Clarifier votre vision et vos objectifs : Donnez une direction claire \u00e0 votre entreprise. Affinez votre direction et votre orientation : Prenez des d\u00e9cisions \u00e9clair\u00e9es et align\u00e9es sur vos ambitions. Inspirez la cr\u00e9ativit\u00e9 et l&rsquo;innovation dans vos processus internes : Stimulez l&rsquo;innovation au c\u0153ur de vos processus. D\u00e9veloppez des strat\u00e9gies de croissance puissantes : Concevez des plans robustes pour une croissance durable. Optimisez vos ressources et maximisez votre rentabilit\u00e9 : Utilisez vos ressources de mani\u00e8re efficiente pour des r\u00e9sultats tangibles. Planifiez et organisez pour le succ\u00e8s : Structurez vos actions pour garantir un avenir prosp\u00e8re. Transformez vos doutes en une force motrice pour une prise de d\u00e9cision strat\u00e9gique et maintenez une motivation \u00e9lev\u00e9e, m\u00eame face aux d\u00e9fis. En Savoir Plus Coaching En Entreprise Envie de transformer votre \u00e9quipe en une force coh\u00e9sive et performante, align\u00e9e sur les objectifs de votre entreprise ? Am\u00e9lioration de la communication : Facilitez les \u00e9changes et renforcez la collaboration. Encouragement de la collaboration : Cr\u00e9ez une dynamique d&rsquo;\u00e9quipe positive et productive. D\u00e9veloppement des comp\u00e9tences en leadership : Formez des leaders capables de guider avec succ\u00e8s. Gestion du changement : Accompagnez vos \u00e9quipes dans les transitions organisationnelles. Motivation des \u00e9quipes : Augmentez l\u2019engagement et la satisfaction au travail. En Savoir Plus Atelier et Formation Des formations sur mesure et des ateliers dynamiques pour transformer votre entreprise : Ma\u00eetrise du temps et efficacit\u00e9 : Dominez votre agenda pour une productivit\u00e9 maximale. Leadership et communication : Devenez un leader inspirant et un communicateur d&rsquo;exception. Gestion du stress : Restez ma\u00eetre de vos \u00e9motions, m\u00eame sous pression. Optimisation fiscale : Maximisez vos avantages fiscaux. Plan d&rsquo;affaires solide : Posez des fondations in\u00e9branlables pour votre succ\u00e8s. Vision strat\u00e9gique : Naviguez avec confiance vers l&rsquo;avenir. En Savoir Plus La m\u00e9thode ISIR : Quatre \u00c9tapes pour R\u00e9ussir le Passage \u00e0 l\u2019Action Identifier Simplifier Impulser Rayonner Identifier :\u00a0Nous r\u00e9v\u00e9lons vos forces et d\u00e9tectons les opportunit\u00e9s pour b\u00e2tir une base solide. Simplifier : Nous \u00e9purons vos processus et relations pour vous concentrer sur l&rsquo;essentiel. Impulser : \u00a0Nous transformons les id\u00e9es en actions concr\u00e8tes pour acc\u00e9l\u00e9rer votre progression. Rayonner: Nous vous accompagnons pour que votre succ\u00e8s soit reconnu et durable.","og_url":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/","og_site_name":"ISIR Conseils","article_modified_time":"2024-08-20T15:53:46+00:00","og_image":[{"url":"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/","url":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/","name":"Nos Services - ISIR Conseils","isPartOf":{"@id":"https:\/\/www.isirconseils.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/#primaryimage"},"image":{"@id":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/#primaryimage"},"thumbnailUrl":"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-scaled.jpg","datePublished":"2024-04-30T13:56:50+00:00","dateModified":"2024-08-20T15:53:46+00:00","breadcrumb":{"@id":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.isirconseils.com\/index.php\/nos-services\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/#primaryimage","url":"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-scaled.jpg","contentUrl":"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/07\/services-min-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.isirconseils.com\/index.php\/nos-services\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.isirconseils.com\/"},{"@type":"ListItem","position":2,"name":"Nos Services"}]},{"@type":"WebSite","@id":"https:\/\/www.isirconseils.com\/#website","url":"https:\/\/www.isirconseils.com\/","name":"ISIR Conseils","description":"","publisher":{"@id":"https:\/\/www.isirconseils.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.isirconseils.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.isirconseils.com\/#organization","name":"ISIR Conseils","url":"https:\/\/www.isirconseils.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.isirconseils.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/06\/Logo-ISIR-web-2.png","contentUrl":"https:\/\/www.isirconseils.com\/wp-content\/uploads\/2024\/06\/Logo-ISIR-web-2.png","width":202,"height":224,"caption":"ISIR Conseils"},"image":{"@id":"https:\/\/www.isirconseils.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/pages\/145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/comments?post=145"}],"version-history":[{"count":132,"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/pages\/145\/revisions"}],"predecessor-version":[{"id":1371,"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/pages\/145\/revisions\/1371"}],"wp:attachment":[{"href":"https:\/\/www.isirconseils.com\/index.php\/wp-json\/wp\/v2\/media?parent=145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}